{"id":4574,"date":"2023-01-20T14:56:42","date_gmt":"2023-01-20T12:56:42","guid":{"rendered":"http:\/\/bn.merianto.com\/tehty-tyo\/"},"modified":"2025-11-16T12:42:25","modified_gmt":"2025-11-16T10:42:25","slug":"tehty-tyo","status":"publish","type":"page","link":"https:\/\/merianto.com\/fi\/tehty-tyo\/","title":{"rendered":"Tehty ty\u00f6"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4574\" class=\"elementor elementor-4574 elementor-2866\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb6f302 elementor-section-height-min-height elementor-section-items-bottom elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"cb6f302\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fe1e47\" data-id=\"5fe1e47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72e623b elementor-widget elementor-widget-heading\" data-id=\"72e623b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Referenssit<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b13733e elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"b13733e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d2336cb\" data-id=\"d2336cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be9ae36 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"be9ae36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Merianto on jo yli 20 vuotta suunnittelut sairaaloiden, terveyskeskusten, apteekkien, hotellien, museoiden, l\u00e4hetyst\u00f6jen, koulujen, p\u00e4iv\u00e4kotien, toimistorakennusten sek\u00e4 kotien kalustusta niin Virossa, Suomessa kuin muuallakin. T\u00e4rkeimpi\u00e4 asiakkaitamme ovat johtavat rakennusliikkeet, jotka ovat uskoneet suunnittelijoiden ja arkkitehtien loisteliaiden k\u00e4yt\u00e4nn\u00f6n toteutuksen meid\u00e4n teht\u00e4v\u00e4ksemme.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b03042c elementor-widget elementor-widget-spacer\" data-id=\"b03042c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bdeae93\" data-id=\"bdeae93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83bc44e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"83bc44e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tavanomaisten kohteiden lis\u00e4ksi Merianto on toteuttanut sisustusprojekteja eritt\u00e4in vaativissa kohteissa. Esimerkkej\u00e4 kohteista: Finlandia-talo, Suomen Kansallisooppera, Saamelaisparlamentti, Pohjois-Viron aluesairaala, Tarton yliopistollinen sairaala, Helsingin ja Uudenmaan sairaanhoitopiiri (HUS), Tampereen ja Turun yliopistolliset saisaalat (TAYS ja TYKS), useat Viron tasavallan suurl\u00e4hetyst\u00f6t ja monet muut kohteet.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9793bd2 elementor-widget elementor-widget-button\" data-id=\"9793bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#sec\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tutustu tehtyihin t\u00f6ihin aikaj\u00e4rjestyksess\u00e4<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-399cb01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"399cb01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31b7dbc\" data-id=\"31b7dbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb33e2e elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"fb33e2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.66000000000000003108624468950438313186168670654296875,&quot;sizes&quot;:[]},&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-portfolio__filters\">\n\t\t\t<li class=\"elementor-portfolio__filter elementor-active\" tabindex=\"0\" data-filter=\"__all\">All<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"177\">Edustuskalusteet<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"179\">Erikoisratkaisut<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"48\">Esindusm\u00f6\u00f6bel<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"171\">Hotelli<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"178\">Keitti\u00f6t ja naulakot<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"176\">Komposiittituotteet<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"46\">Komposiittooted<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"183\">Koulu ja p\u00e4iv\u00e4koti<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"189\">Lasiv\u00e4lisein\u00e4t ja ovet<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"181\">Sein\u00e4paneelit<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"185\">Toimisto<\/li>\n\t\t\t\t\t\t\t<li class=\"elementor-portfolio__filter\" tabindex=\"0\" data-filter=\"187\">WC-v\u00e4lisein\u00e4t<\/li>\n\t\t\t\t\t<\/ul>\n\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-178 elementor-filter-176 elementor-filter-46 elementor-filter-185 post-10966 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-komposiittituotteet portfolio_category-komposiittooted portfolio_category-toimisto\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/erica_chemistry_park\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1094\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M24115_Erica_6.jpg\" class=\"attachment-full size-full wp-image-10924\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M24115_Erica_6.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M24115_Erica_6-300x171.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M24115_Erica_6-1024x583.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M24115_Erica_6-768x438.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M24115_Erica_6-1536x875.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEriCa Green Chemistry Park\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-181 post-10701 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/lyyra\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1221\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/05\/Lyyra_1.jpg\" class=\"attachment-full size-full wp-image-10801\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/05\/Lyyra_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/05\/Lyyra_1-300x191.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/05\/Lyyra_1-1024x651.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/05\/Lyyra_1-768x488.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/05\/Lyyra_1-1536x977.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tLyyra\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-178 post-11088 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/medicum\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1274\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/Medicum_aula-2.jpg\" class=\"attachment-full size-full wp-image-11037\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/Medicum_aula-2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/Medicum_aula-2-300x199.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/Medicum_aula-2-1024x679.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/Medicum_aula-2-768x510.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/Medicum_aula-2-1536x1019.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMedicum Terveyskeskus\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-178 elementor-filter-185 post-10610 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-toimisto\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/health_insurance_fund\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TKassa_Merianto_2.jpg\" class=\"attachment-full size-full wp-image-10556\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TKassa_Merianto_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TKassa_Merianto_2-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TKassa_Merianto_2-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TKassa_Merianto_2-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TKassa_Merianto_2-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHealth Insurance Fund\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-10493 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/woodcity-toimisto-2\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1434\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/WoodCity_1.jpg\" class=\"attachment-full size-full wp-image-10454\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/WoodCity_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/WoodCity_1-300x224.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/WoodCity_1-1024x765.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/WoodCity_1-768x574.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/WoodCity_1-1536x1147.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tWoodcity Toimisto 2\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-181 elementor-filter-185 post-10667 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit portfolio_category-toimisto\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/katajanokan_laituri\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/KNL_10.jpg\" class=\"attachment-full size-full wp-image-10655\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/KNL_10.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/KNL_10-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/KNL_10-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/KNL_10-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/KNL_10-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKatajanokan Laituri\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-48 post-10420 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-esindusmoobel\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/ilmalan_aura\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/Ilmalan_AURA_1.jpg\" class=\"attachment-full size-full wp-image-10408\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/Ilmalan_AURA_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/Ilmalan_AURA_1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/Ilmalan_AURA_1-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/Ilmalan_AURA_1-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/09\/Ilmalan_AURA_1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIlmalan Aura\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-48 elementor-filter-176 elementor-filter-46 elementor-filter-181 post-10895 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-esindusmoobel portfolio_category-komposiittituotteet portfolio_category-komposiittooted portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/finlandia_talo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M23078_Finlandiatalo_1.jpg\" class=\"attachment-full size-full wp-image-10853\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M23078_Finlandiatalo_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M23078_Finlandiatalo_1-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M23078_Finlandiatalo_1-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M23078_Finlandiatalo_1-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/11\/M23078_Finlandiatalo_1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFinlandia Talo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-48 elementor-filter-181 post-10838 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-esindusmoobel portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/toas-hippos-ravintola\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TOAS_Hippos-ravintola_56.jpg\" class=\"attachment-full size-full wp-image-10689\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TOAS_Hippos-ravintola_56.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TOAS_Hippos-ravintola_56-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TOAS_Hippos-ravintola_56-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TOAS_Hippos-ravintola_56-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2025\/01\/TOAS_Hippos-ravintola_56-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTOAS Hippos Ravintola\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-171 post-9470 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-hotelli\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/noli-tjk-herttoniemi\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NOLI-TJK-Herttoniemi-1.jpg\" class=\"attachment-full size-full wp-image-4768\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NOLI-TJK-Herttoniemi-1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NOLI-TJK-Herttoniemi-1-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NOLI-TJK-Herttoniemi-1-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NOLI-TJK-Herttoniemi-1-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NOLI-TJK-Herttoniemi-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNOLI TJK Herttoniemi\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-171 post-9479 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-hotelli\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/hotelli-omenatarha-kisakallio\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Hotelli_Omenatarha_Kisakallio_7.jpg\" class=\"attachment-full size-full wp-image-5349\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Hotelli_Omenatarha_Kisakallio_7.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Hotelli_Omenatarha_Kisakallio_7-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Hotelli_Omenatarha_Kisakallio_7-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Hotelli_Omenatarha_Kisakallio_7-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Hotelli_Omenatarha_Kisakallio_7-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHotelli Omenatarha Kisakallio\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-181 post-10294 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/runosmaen_monitoimitalo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1285\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Runosmaen_Monitoimitalo_9.jpg\" class=\"attachment-full size-full wp-image-10271\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Runosmaen_Monitoimitalo_9.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Runosmaen_Monitoimitalo_9-300x201.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Runosmaen_Monitoimitalo_9-1024x685.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Runosmaen_Monitoimitalo_9-768x514.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Runosmaen_Monitoimitalo_9-1536x1028.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRunosm\u00e4en Monitoimitalo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-178 elementor-filter-176 post-9485 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-komposiittituotteet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/tartu-university-hospital-m-and-c-corps\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TUK_Maarjamoisa_23.jpg\" class=\"attachment-full size-full wp-image-8979\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TUK_Maarjamoisa_23.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TUK_Maarjamoisa_23-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TUK_Maarjamoisa_23-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TUK_Maarjamoisa_23-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TUK_Maarjamoisa_23-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTartu University Hospital, M- and C-corps\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9504 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/mevet-elainsairaala\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Mevet-Elainsairaala-1.jpg\" class=\"attachment-full size-full wp-image-4695\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Mevet-Elainsairaala-1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Mevet-Elainsairaala-1-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Mevet-Elainsairaala-1-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Mevet-Elainsairaala-1-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Mevet-Elainsairaala-1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMevet El\u00e4insairaala\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-181 post-10305 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/lippulaivan-kirjasto-2\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1393\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Rocca_Towers_1.jpg\" class=\"attachment-full size-full wp-image-10311\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Rocca_Towers_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Rocca_Towers_1-300x218.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Rocca_Towers_1-1024x743.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Rocca_Towers_1-768x557.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Rocca_Towers_1-1536x1114.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRocca Towers\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-171 post-9510 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-hotelli\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/solo-sokos-hotel-torni\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1356\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Solo-Sokos-Hotel-Torni-12.jpg\" class=\"attachment-full size-full wp-image-4800\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Solo-Sokos-Hotel-Torni-12.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Solo-Sokos-Hotel-Torni-12-300x212.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Solo-Sokos-Hotel-Torni-12-1024x723.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Solo-Sokos-Hotel-Torni-12-768x542.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Solo-Sokos-Hotel-Torni-12-1536x1085.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSolo Sokos Hotel Torni\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-176 post-9519 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-komposiittituotteet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/meilahden-siltasairaala\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Siltasairaala_8a.jpg\" class=\"attachment-full size-full wp-image-8800\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Siltasairaala_8a.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Siltasairaala_8a-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Siltasairaala_8a-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Siltasairaala_8a-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Siltasairaala_8a-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMeilahden Siltasairaala\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-181 post-9529 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/bulevardin-toimisto\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haahtela_Bulevardi_verhoilu_5.jpg\" class=\"attachment-full size-full wp-image-8910\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haahtela_Bulevardi_verhoilu_5.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haahtela_Bulevardi_verhoilu_5-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haahtela_Bulevardi_verhoilu_5-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haahtela_Bulevardi_verhoilu_5-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haahtela_Bulevardi_verhoilu_5-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tBulevardin toimisto\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-9535 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/lippulaivan-kirjasto\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Lippulaivan_kirjasto_3.jpg\" class=\"attachment-full size-full wp-image-7640\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Lippulaivan_kirjasto_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Lippulaivan_kirjasto_3-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Lippulaivan_kirjasto_3-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Lippulaivan_kirjasto_3-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Lippulaivan_kirjasto_3-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tLippulaivan kirjasto\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-178 elementor-filter-176 post-9540 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-komposiittituotteet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/medicumin-perhelaakarikeskus\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1265\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Medicum_Perearstikeskus_1.jpg\" class=\"attachment-full size-full wp-image-8704\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Medicum_Perearstikeskus_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Medicum_Perearstikeskus_1-300x198.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Medicum_Perearstikeskus_1-1024x675.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Medicum_Perearstikeskus_1-768x506.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Medicum_Perearstikeskus_1-1536x1012.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMedicumin perhel\u00e4\u00e4k\u00e4rikeskus\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-9545 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/viron-suurlahetysto-roomassa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1281\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Ambasc_Estonia_Roma_4.jpg\" class=\"attachment-full size-full wp-image-5114\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Ambasc_Estonia_Roma_4.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Ambasc_Estonia_Roma_4-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Ambasc_Estonia_Roma_4-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Ambasc_Estonia_Roma_4-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Ambasc_Estonia_Roma_4-1536x1025.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tViron suurl\u00e4hetyst\u00f6 Roomassa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-183 post-9550 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/leppavaaran-monikko\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Monikko-2.jpg\" class=\"attachment-full size-full wp-image-4965\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Monikko-2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Monikko-2-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Monikko-2-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Monikko-2-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Monikko-2-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tLepp\u00e4vaaran Monikko\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-178 post-9557 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/hus-puistosairaala\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1282\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Puistosairaala_4.jpg\" class=\"attachment-full size-full wp-image-8731\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Puistosairaala_4.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Puistosairaala_4-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Puistosairaala_4-1024x684.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Puistosairaala_4-768x513.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HUS_Puistosairaala_4-1536x1026.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHUS Puistosairaala\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-178 elementor-filter-185 post-9562 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-toimisto\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/kalasataman-kampus\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/K_Group_laajennus_1.jpg\" class=\"attachment-full size-full wp-image-4908\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/K_Group_laajennus_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/K_Group_laajennus_1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/K_Group_laajennus_1-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/K_Group_laajennus_1-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/K_Group_laajennus_1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKalasataman Kampus\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-171 post-9565 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-hotelli\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/holiday-inn-helsinki-expo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Messuhotelli-1-lobby-1.jpg\" class=\"attachment-full size-full wp-image-5183\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Messuhotelli-1-lobby-1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Messuhotelli-1-lobby-1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Messuhotelli-1-lobby-1-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Messuhotelli-1-lobby-1-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Messuhotelli-1-lobby-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHoliday Inn Helsinki \u2013 Expo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-176 post-9576 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-komposiittituotteet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/turun-yliopistollinen-keskussairaala\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TYKS_T3_Turku_4.jpg\" class=\"attachment-full size-full wp-image-8671\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TYKS_T3_Turku_4.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TYKS_T3_Turku_4-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TYKS_T3_Turku_4-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TYKS_T3_Turku_4-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/TYKS_T3_Turku_4-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTurun Yliopistollinen Keskussairaala\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9582 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/tampereen-yliopistollinen-sairaala-tays\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/TAYS_Hospital_Tampere_D_wing_1.jpg\" class=\"attachment-full size-full wp-image-5606\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/TAYS_Hospital_Tampere_D_wing_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/TAYS_Hospital_Tampere_D_wing_1-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/TAYS_Hospital_Tampere_D_wing_1-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/TAYS_Hospital_Tampere_D_wing_1-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/TAYS_Hospital_Tampere_D_wing_1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTampereen yliopistollinen sairaala (TAYS)\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-178 post-9589 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/laane-tallinnan-keskussairaala-6-kerros\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/LTKH_6krs_2.jpg\" class=\"attachment-full size-full wp-image-8656\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/LTKH_6krs_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/LTKH_6krs_2-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/LTKH_6krs_2-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/LTKH_6krs_2-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/LTKH_6krs_2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tL\u00e4\u00e4ne-Tallinnan keskussairaala, 6. kerros\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-9594 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/amos-rex-taidemuseo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Amos_Rex-Museo_Helsinki_3.jpg\" class=\"attachment-full size-full wp-image-5369\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Amos_Rex-Museo_Helsinki_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Amos_Rex-Museo_Helsinki_3-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Amos_Rex-Museo_Helsinki_3-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Amos_Rex-Museo_Helsinki_3-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Amos_Rex-Museo_Helsinki_3-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAmos Rex taidemuseo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-181 post-9602 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/opiku-toimistotalo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1381\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Opiku_Arimaja_fuajee_2.jpg\" class=\"attachment-full size-full wp-image-5150\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Opiku_Arimaja_fuajee_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Opiku_Arimaja_fuajee_2-300x216.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Opiku_Arimaja_fuajee_2-1024x737.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Opiku_Arimaja_fuajee_2-768x552.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Opiku_Arimaja_fuajee_2-1536x1105.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\t\u00d6piku Toimistotalo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-181 post-9605 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/maakri-talo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Maakri_Tower_halls_7.jpg\" class=\"attachment-full size-full wp-image-5420\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Maakri_Tower_halls_7.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Maakri_Tower_halls_7-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Maakri_Tower_halls_7-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Maakri_Tower_halls_7-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Maakri_Tower_halls_7-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMaakri talo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-10191 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/ncc-toimistotalo-2\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1169\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Stockmann_Ravintolat_1.jpg\" class=\"attachment-full size-full wp-image-10199\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Stockmann_Ravintolat_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Stockmann_Ravintolat_1-300x183.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Stockmann_Ravintolat_1-1024x623.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Stockmann_Ravintolat_1-768x468.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/Stockmann_Ravintolat_1-1536x935.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tStockmann ravintolamaailma\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9612 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/ncc-toimistotalo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NCC_Toimistotalo_showroom_3.jpg\" class=\"attachment-full size-full wp-image-5684\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NCC_Toimistotalo_showroom_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NCC_Toimistotalo_showroom_3-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NCC_Toimistotalo_showroom_3-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NCC_Toimistotalo_showroom_3-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/NCC_Toimistotalo_showroom_3-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNCC Toimistotalo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9618 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/fastighets-ab-glaspalatset-i-helsingfors-lasipalatsi-helsinki\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1397\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lasipalatsi_5.jpg\" class=\"attachment-full size-full wp-image-5670\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lasipalatsi_5.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lasipalatsi_5-300x218.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lasipalatsi_5-1024x745.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lasipalatsi_5-768x559.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lasipalatsi_5-1536x1118.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFastighets Ab Glaspalatset i Helsingfors \u2013 Lasipalatsi Helsinki\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9626 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/metropolia-koulutuskeskus\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Metrolia_koulutuskeskus_2.jpg\" class=\"attachment-full size-full wp-image-5484\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Metrolia_koulutuskeskus_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Metrolia_koulutuskeskus_2-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Metrolia_koulutuskeskus_2-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Metrolia_koulutuskeskus_2-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Metrolia_koulutuskeskus_2-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMetropolia Koulutuskeskus\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-171 post-9632 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-hotelli\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/palace-royal-ravintolat\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1376\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Palace_Royal_Ravintolat_3.jpg\" class=\"attachment-full size-full wp-image-5446\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Palace_Royal_Ravintolat_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Palace_Royal_Ravintolat_3-300x215.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Palace_Royal_Ravintolat_3-1024x734.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Palace_Royal_Ravintolat_3-768x550.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Palace_Royal_Ravintolat_3-1536x1101.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPalace Royal Ravintolat\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-178 elementor-filter-185 post-9640 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-toimisto\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/vaaksyntie-toimistotalo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vaaksyntie_toimisto_4.jpg\" class=\"attachment-full size-full wp-image-5860\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vaaksyntie_toimisto_4.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vaaksyntie_toimisto_4-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vaaksyntie_toimisto_4-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vaaksyntie_toimisto_4-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vaaksyntie_toimisto_4-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tV\u00e4\u00e4ksyntie toimistotalo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-185 post-9645 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-toimisto\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/handelsbanken-helsinki\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Handelsbanken_Helsinki_8.jpg\" class=\"attachment-full size-full wp-image-5809\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Handelsbanken_Helsinki_8.jpg 1600w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Handelsbanken_Helsinki_8-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Handelsbanken_Helsinki_8-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Handelsbanken_Helsinki_8-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Handelsbanken_Helsinki_8-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHandelsbanken Helsinki\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-178 post-9654 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/smartly-io\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Smartly_office_3.jpg\" class=\"attachment-full size-full wp-image-5779\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Smartly_office_3.jpg 1600w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Smartly_office_3-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Smartly_office_3-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Smartly_office_3-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Smartly_office_3-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSmartly.io\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-9660 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/exel-esittelytila\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1763\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/EXEL_showroom_1.jpg\" class=\"attachment-full size-full wp-image-5923\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/EXEL_showroom_1.jpg 1763w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/EXEL_showroom_1-300x204.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/EXEL_showroom_1-1024x697.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/EXEL_showroom_1-768x523.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/EXEL_showroom_1-1536x1045.jpg 1536w\" sizes=\"(max-width: 1763px) 100vw, 1763px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEXEL esittelytila\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-181 post-9666 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/nurmijarven-monikko\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Nurmijarven_Monikko_4.jpg\" class=\"attachment-full size-full wp-image-5721\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Nurmijarven_Monikko_4.jpg 1600w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Nurmijarven_Monikko_4-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Nurmijarven_Monikko_4-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Nurmijarven_Monikko_4-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Nurmijarven_Monikko_4-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNurmij\u00e4rven Monikko\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-176 elementor-filter-187 post-9672 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-komposiittituotteet portfolio_category-wc-valiseinat\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/hanasaare-kulttuurikeskus\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1205\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hanasaaren_Kulttuurikeskus_1.jpg\" class=\"attachment-full size-full wp-image-6637\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hanasaaren_Kulttuurikeskus_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hanasaaren_Kulttuurikeskus_1-300x188.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hanasaaren_Kulttuurikeskus_1-1024x643.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hanasaaren_Kulttuurikeskus_1-768x482.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hanasaaren_Kulttuurikeskus_1-1536x964.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHanasaare kulttuurikeskus\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-187 post-9681 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-wc-valiseinat\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/lansiterminaali-2\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1350\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lansisatam_MT2_matkustajaterminaali_8-1.jpg\" class=\"attachment-full size-full wp-image-5571\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lansisatam_MT2_matkustajaterminaali_8-1.jpg 1800w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lansisatam_MT2_matkustajaterminaali_8-1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lansisatam_MT2_matkustajaterminaali_8-1-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lansisatam_MT2_matkustajaterminaali_8-1-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Lansisatam_MT2_matkustajaterminaali_8-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tL\u00e4nsiterminaali 2\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9686 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/vantaan-energia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1494\" height=\"1157\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vantaan_Energia_2.jpg\" class=\"attachment-full size-full wp-image-6416\" alt=\"olid glass walls, decorative glass-wallpanels, oak veneered doors\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vantaan_Energia_2.jpg 1494w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vantaan_Energia_2-300x232.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vantaan_Energia_2-1024x793.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Vantaan_Energia_2-768x595.jpg 768w\" sizes=\"(max-width: 1494px) 100vw, 1494px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tVantaan Energia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-10180 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/hanasaare-kulttuurikeskus-2\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"990\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/SandroTapiola_Tuulikinsilta_1.jpg\" class=\"attachment-full size-full wp-image-10159\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/SandroTapiola_Tuulikinsilta_1.jpg 1500w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/SandroTapiola_Tuulikinsilta_1-300x198.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/SandroTapiola_Tuulikinsilta_1-1024x676.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/04\/SandroTapiola_Tuulikinsilta_1-768x507.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSandro Tapiola Restaurant\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-181 post-9691 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/fennia-pasilanportti\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"932\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Fennia_Pasilanportti_20.jpg\" class=\"attachment-full size-full wp-image-6708\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Fennia_Pasilanportti_20.jpg 1200w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Fennia_Pasilanportti_20-300x233.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Fennia_Pasilanportti_20-1024x795.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Fennia_Pasilanportti_20-768x596.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFennia Pasilanportti\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-171 post-9698 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-hotelli\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/clarion-hotel-helsinki\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Clarion_Hotel_Helsinki_2.jpg\" class=\"attachment-full size-full wp-image-5962\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Clarion_Hotel_Helsinki_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Clarion_Hotel_Helsinki_2-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Clarion_Hotel_Helsinki_2-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Clarion_Hotel_Helsinki_2-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Clarion_Hotel_Helsinki_2-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tClarion Hotel Helsinki\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-183 post-9703 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/aalto-kampuskirjasto\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1667\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Aalto_Yliopisto_library_1.jpg\" class=\"attachment-full size-full wp-image-6344\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Aalto_Yliopisto_library_1.jpg 1667w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Aalto_Yliopisto_library_1-300x216.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Aalto_Yliopisto_library_1-1024x737.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Aalto_Yliopisto_library_1-768x553.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Aalto_Yliopisto_library_1-1536x1106.jpg 1536w\" sizes=\"(max-width: 1667px) 100vw, 1667px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAALTO Kampuskirjasto\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9709 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/tampereen-kansanvalinen-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1166\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_60.jpg\" class=\"attachment-full size-full wp-image-6129\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_60.jpg 1500w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_60-300x233.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_60-1024x796.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_60-768x597.jpg 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTampereen kansanv\u00e4linen koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-183 post-9714 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/svenska-normallyceum-helsinki\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1773\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Svenska_Normallyceum_12.jpg\" class=\"attachment-full size-full wp-image-6266\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Svenska_Normallyceum_12.jpg 1773w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Svenska_Normallyceum_12-300x203.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Svenska_Normallyceum_12-1024x693.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Svenska_Normallyceum_12-768x520.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Svenska_Normallyceum_12-1536x1040.jpg 1536w\" sizes=\"(max-width: 1773px) 100vw, 1773px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSvenska Normallyceum Helsinki\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-183 post-9721 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/fista-tampereen-kansainvalinen-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1792\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_5.jpg\" class=\"attachment-full size-full wp-image-6099\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_5.jpg 1792w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_5-300x201.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_5-1024x686.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_5-768x514.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/FISTA_Koulu_Tampere_5-1536x1029.jpg 1536w\" sizes=\"(max-width: 1792px) 100vw, 1792px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFISTA, Tampereen kansainv\u00e4linen koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-183 post-9726 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/tuomelan-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/KOTA_learning_space_module_6.jpg\" class=\"attachment-full size-full wp-image-6314\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/KOTA_learning_space_module_6.jpg 1600w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/KOTA_learning_space_module_6-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/KOTA_learning_space_module_6-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/KOTA_learning_space_module_6-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/KOTA_learning_space_module_6-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTuomelan Koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-178 elementor-filter-176 elementor-filter-183 post-9731 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-komposiittituotteet portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/valteri-koulu-onerva-jyvaskyla\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1390\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Valteri_koulu_Onerva_22.jpg\" class=\"attachment-full size-full wp-image-6903\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Valteri_koulu_Onerva_22.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Valteri_koulu_Onerva_22-300x217.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Valteri_koulu_Onerva_22-1024x741.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Valteri_koulu_Onerva_22-768x556.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Valteri_koulu_Onerva_22-1536x1112.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tValteri-koulu Onerva Jyv\u00e4skyl\u00e4\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-183 post-9737 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/hirvikosken-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1132\" height=\"1483\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hirvikosken_Koulu_2.jpg\" class=\"attachment-full size-full wp-image-7253\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hirvikosken_Koulu_2.jpg 1132w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hirvikosken_Koulu_2-229x300.jpg 229w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hirvikosken_Koulu_2-782x1024.jpg 782w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hirvikosken_Koulu_2-768x1006.jpg 768w\" sizes=\"(max-width: 1132px) 100vw, 1132px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHirvikosken koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 elementor-filter-181 post-9742 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/helsingin-unioninkatu-yliopistu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1277\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HelsinginYliopistoUnioninkatu_3.jpg\" class=\"attachment-full size-full wp-image-7235\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HelsinginYliopistoUnioninkatu_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HelsinginYliopistoUnioninkatu_3-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HelsinginYliopistoUnioninkatu_3-1024x681.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HelsinginYliopistoUnioninkatu_3-768x511.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HelsinginYliopistoUnioninkatu_3-1536x1022.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHelsingin Unioninkatu yliopistu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9749 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/kiinteisto-oy-estradi\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1322\" height=\"1125\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Estradi_toimisto_1.jpg\" class=\"attachment-full size-full wp-image-7172\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Estradi_toimisto_1.jpg 1322w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Estradi_toimisto_1-300x255.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Estradi_toimisto_1-1024x871.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Estradi_toimisto_1-768x654.jpg 768w\" sizes=\"(max-width: 1322px) 100vw, 1322px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKiinteist\u00f6 Oy Estradi\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-9754 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/kansalliskirjastoon\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"2000\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kansalliskirjasto_1.jpg\" class=\"attachment-full size-full wp-image-6776\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kansalliskirjasto_1.jpg 1500w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kansalliskirjasto_1-225x300.jpg 225w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kansalliskirjasto_1-768x1024.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kansalliskirjasto_1-1152x1536.jpg 1152w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKansalliskirjastoon\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-178 post-9759 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/huslab-helsingin-yliopistokiinteistot\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1438\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HusLab_Toimisto_1.jpg\" class=\"attachment-full size-full wp-image-7304\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HusLab_Toimisto_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HusLab_Toimisto_1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HusLab_Toimisto_1-1024x767.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HusLab_Toimisto_1-768x575.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HusLab_Toimisto_1-1536x1150.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHusLab, Helsingin Yliopistokiinteist\u00f6t\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-171 post-9764 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-hotelli\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/hotel-indigo-bulevardi-helsinki\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1595\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HotelI_Indigo_14.jpg\" class=\"attachment-full size-full wp-image-7436\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HotelI_Indigo_14.jpg 1595w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HotelI_Indigo_14-300x226.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HotelI_Indigo_14-1024x770.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HotelI_Indigo_14-768x578.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/HotelI_Indigo_14-1536x1156.jpg 1536w\" sizes=\"(max-width: 1595px) 100vw, 1595px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHotel Indigo Bulevardi Helsinki\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-178 elementor-filter-176 post-9771 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-keittiot-ja-naulakot portfolio_category-komposiittituotteet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/terveyden-ja-hyvinvoinnin-laitos-thl\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1495\" height=\"1168\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/THL_9.jpg\" class=\"attachment-full size-full wp-image-6806\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/THL_9.jpg 1495w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/THL_9-300x234.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/THL_9-1024x800.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/THL_9-768x600.jpg 768w\" sizes=\"(max-width: 1495px) 100vw, 1495px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTerveyden ja hyvinvoinnin laitos (THL)\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-181 post-9781 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/karakallion-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Karakallion_koulu_auditorio_3.jpg\" class=\"attachment-full size-full wp-image-7628\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Karakallion_koulu_auditorio_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Karakallion_koulu_auditorio_3-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Karakallion_koulu_auditorio_3-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Karakallion_koulu_auditorio_3-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Karakallion_koulu_auditorio_3-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKarakallion koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9789 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/tallinnan-piispallinen-tuomiokirkko\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"2377\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toomkirik_2.jpg\" class=\"attachment-full size-full wp-image-7385\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toomkirik_2.jpg 1800w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toomkirik_2-227x300.jpg 227w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toomkirik_2-775x1024.jpg 775w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toomkirik_2-768x1014.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toomkirik_2-1163x1536.jpg 1163w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toomkirik_2-1551x2048.jpg 1551w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTallinnan piispallinen tuomiokirkko\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-9795 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/viron-suurlahetysto-pekingissa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/M4016_3.jpg\" class=\"attachment-full size-full wp-image-7355\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/M4016_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/M4016_3-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/M4016_3-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/M4016_3-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/M4016_3-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tViron suurl\u00e4hetyst\u00f6 Pekingiss\u00e4\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-181 post-9800 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/alberga-c-talo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Alberga_C_2a-1.jpg\" class=\"attachment-full size-full wp-image-7505\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Alberga_C_2a-1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Alberga_C_2a-1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Alberga_C_2a-1-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Alberga_C_2a-1-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Alberga_C_2a-1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAlberga C-talo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-178 post-9805 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/malmin-sairaala\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1466\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Malmin_sairaala_2.jpg\" class=\"attachment-full size-full wp-image-7541\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Malmin_sairaala_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Malmin_sairaala_2-300x229.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Malmin_sairaala_2-1024x782.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Malmin_sairaala_2-768x586.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Malmin_sairaala_2-1536x1173.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMalmin sairaala\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-178 post-9811 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/nordea-akk7-toimisto\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1293\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nordea_AKK7_8.jpg\" class=\"attachment-full size-full wp-image-8008\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nordea_AKK7_8.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nordea_AKK7_8-300x202.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nordea_AKK7_8-1024x690.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nordea_AKK7_8-768x517.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nordea_AKK7_8-1536x1034.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNordea AKK7 toimisto\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9817 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/suomen-luontokeskus-haltia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1331\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nuuksiokeskus_2.jpg\" class=\"attachment-full size-full wp-image-8110\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nuuksiokeskus_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nuuksiokeskus_2-300x208.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nuuksiokeskus_2-1024x710.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nuuksiokeskus_2-768x532.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Nuuksiokeskus_2-1536x1065.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSuomen Luontokeskus Haltia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9823 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/toolonlahden-toimistotalo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toolonlahden_toimistotalo_5-scaled.jpg\" class=\"attachment-full size-full wp-image-8596\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toolonlahden_toimistotalo_5-scaled.jpg 1707w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toolonlahden_toimistotalo_5-200x300.jpg 200w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toolonlahden_toimistotalo_5-683x1024.jpg 683w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toolonlahden_toimistotalo_5-768x1152.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toolonlahden_toimistotalo_5-1024x1536.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Toolonlahden_toimistotalo_5-1365x2048.jpg 1365w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tT\u00f6\u00f6l\u00f6nlahden Toimistotalo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 elementor-filter-187 post-9829 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut portfolio_category-wc-valiseinat\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/haukilahden-vesitorni\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haukilahden_Vesitorni_2.jpg\" class=\"attachment-full size-full wp-image-8626\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haukilahden_Vesitorni_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haukilahden_Vesitorni_2-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haukilahden_Vesitorni_2-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haukilahden_Vesitorni_2-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Haukilahden_Vesitorni_2-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHaukilahden Vesitorni\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9836 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/hyvinkaan-virastotalo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hyvinkaan_Virastotalo_1.jpg\" class=\"attachment-full size-full wp-image-8408\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hyvinkaan_Virastotalo_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hyvinkaan_Virastotalo_1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hyvinkaan_Virastotalo_1-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hyvinkaan_Virastotalo_1-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Hyvinkaan_Virastotalo_1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHyvink\u00e4\u00e4n Virastotalo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-178 post-9841 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-keittiot-ja-naulakot\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/toimistotalo-triotto\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1430\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Triotto_toimistotalo_1.jpg\" class=\"attachment-full size-full wp-image-7979\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Triotto_toimistotalo_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Triotto_toimistotalo_1-300x223.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Triotto_toimistotalo_1-1024x763.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Triotto_toimistotalo_1-768x572.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Triotto_toimistotalo_1-1536x1144.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tToimistotalo Triotto\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-183 post-9847 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/harjunrinteen-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1436\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Harjunrinteen_koulu_1.jpg\" class=\"attachment-full size-full wp-image-8041\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Harjunrinteen_koulu_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Harjunrinteen_koulu_1-300x224.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Harjunrinteen_koulu_1-1024x766.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Harjunrinteen_koulu_1-768x574.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Harjunrinteen_koulu_1-1536x1149.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHarjunrinteen Koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9852 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/viikin-ymparistotalo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"2400\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Viikin_Ymparistotalo_2.jpg\" class=\"attachment-full size-full wp-image-8566\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Viikin_Ymparistotalo_2.jpg 1800w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Viikin_Ymparistotalo_2-225x300.jpg 225w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Viikin_Ymparistotalo_2-768x1024.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Viikin_Ymparistotalo_2-1152x1536.jpg 1152w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Viikin_Ymparistotalo_2-1536x2048.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tViikin Ymp\u00e4rist\u00f6talo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-178 elementor-filter-183 post-9857 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-keittiot-ja-naulakot portfolio_category-koulu-ja-paivakoti\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/paivakoti-miili\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1728\" height=\"1152\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Miilin_Paivakoti_11.jpg\" class=\"attachment-full size-full wp-image-8371\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Miilin_Paivakoti_11.jpg 1728w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Miilin_Paivakoti_11-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Miilin_Paivakoti_11-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Miilin_Paivakoti_11-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Miilin_Paivakoti_11-1536x1024.jpg 1536w\" sizes=\"(max-width: 1728px) 100vw, 1728px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tP\u00e4iv\u00e4koti Miili\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-183 elementor-filter-189 post-9862 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-koulu-ja-paivakoti portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/kuntolan-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1117\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kuntolan_Koulu_5.jpg\" class=\"attachment-full size-full wp-image-8509\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kuntolan_Koulu_5.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kuntolan_Koulu_5-300x175.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kuntolan_Koulu_5-1024x596.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kuntolan_Koulu_5-768x447.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kuntolan_Koulu_5-1536x894.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKuntolan Koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9868 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/kanniston-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1698\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kanniston_koulu_1.jpg\" class=\"attachment-full size-full wp-image-8479\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kanniston_koulu_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kanniston_koulu_1-300x265.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kanniston_koulu_1-1024x906.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kanniston_koulu_1-768x679.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Kanniston_koulu_1-1536x1358.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKanniston Koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-179 post-9876 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/wanha-villatehdas-kahvila\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Wanha_-Villatehdas_2.jpg\" class=\"attachment-full size-full wp-image-8290\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Wanha_-Villatehdas_2.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Wanha_-Villatehdas_2-300x169.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Wanha_-Villatehdas_2-1024x576.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Wanha_-Villatehdas_2-768x432.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Wanha_-Villatehdas_2-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tWanha Villatehdas kahvila\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 post-9882 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/finlandia-talo-ravintola\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Finlandia_Talo_1.jpg\" class=\"attachment-full size-full wp-image-8269\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Finlandia_Talo_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Finlandia_Talo_1-300x225.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Finlandia_Talo_1-1024x768.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Finlandia_Talo_1-768x576.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Finlandia_Talo_1-1536x1152.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFinlandia Talo ravintola\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-177 elementor-filter-179 elementor-filter-181 elementor-filter-185 post-9888 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-edustuskalusteet portfolio_category-erikoisratkaisut portfolio_category-seinapaneelit portfolio_category-toimisto\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/gustav-paulig-kahvipaahtimo\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Paulig_kahvipaahtimo_1.jpg\" class=\"attachment-full size-full wp-image-8155\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Paulig_kahvipaahtimo_1.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Paulig_kahvipaahtimo_1-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Paulig_kahvipaahtimo_1-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Paulig_kahvipaahtimo_1-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Paulig_kahvipaahtimo_1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGustav Paulig kahvipaahtimo\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9893 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/riigikogun-kanslia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1200\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Riigikogu_Kantselei_1.jpg\" class=\"attachment-full size-full wp-image-8425\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Riigikogu_Kantselei_1.jpg 1800w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Riigikogu_Kantselei_1-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Riigikogu_Kantselei_1-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Riigikogu_Kantselei_1-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Riigikogu_Kantselei_1-1536x1024.jpg 1536w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRiigikogun kanslia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-189 post-9899 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/gatehouse-vuosaari\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Gatehouse_Vuosaari_3.jpg\" class=\"attachment-full size-full wp-image-8236\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Gatehouse_Vuosaari_3.jpg 1920w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Gatehouse_Vuosaari_3-300x200.jpg 300w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Gatehouse_Vuosaari_3-1024x683.jpg 1024w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Gatehouse_Vuosaari_3-768x512.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2024\/01\/Gatehouse_Vuosaari_3-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGatehouse Vuosaari\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post elementor-filter-183 elementor-filter-189 post-9904 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-koulu-ja-paivakoti portfolio_category-lasivaliseinat-ja-ovet\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/merianto.com\/fi\/portfolio\/auroran-koulu\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Auroran_Koulu_2.jpg\" class=\"attachment-full size-full wp-image-6158\" alt=\"\" srcset=\"https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Auroran_Koulu_2.jpg 1200w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Auroran_Koulu_2-225x300.jpg 225w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Auroran_Koulu_2-768x1024.jpg 768w, https:\/\/www.merianto.com\/wp-content\/uploads\/2023\/12\/Auroran_Koulu_2-1152x1536.jpg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAuroran Koulu\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb69e5e elementor-widget elementor-widget-menu-anchor\" data-id=\"fb69e5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"sec\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffd0c48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffd0c48\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-551b0bc\" data-id=\"551b0bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dea93f elementor-widget elementor-widget-accordion\" data-id=\"5dea93f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9841\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9841\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2025<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9841\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9841\"><p><strong>EriCa Green Chemistry Park (Haahtela)<\/strong> &#8211; tutkimuskeskuksen keitti\u00f6t, naulakot, lokerikot, allastasot ja erikoiskalusteet <a href=\"https:\/\/merianto.com\/fi\/portfolio\/erica_chemistry_park\/\">(gallery)<\/a><\/p><p><strong>Laferme (KRC Ehitus)<\/strong> &#8211; asuntotalon k\u00e4yt\u00e4vien sein\u00e4verhoilu<\/p><p><strong>Lammin Koulukeskus (Lapti)<\/strong> &#8211; koulun sis\u00e4ovien toimitus<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9842\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-9842\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2024<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9842\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-9842\"><p><strong>TOAS Hippos Ravintola (Skanska)<\/strong> &#8211; ravintolan tiskilinjastot <a href=\"https:\/\/merianto.com\/fi\/portfolio\/toas-hippos-ravintola\/\">(gallery)<\/a><\/p><p><strong>Health Insurance Fund Estonia<\/strong> &#8211; toimiston erikoiskalusteet, lokerikot, naulakot, keitti\u00f6t <a href=\"https:\/\/merianto.com\/fi\/portfolio\/health_insurance_fund\/\">(gallery)<\/a><\/p><p><strong>Woodcity Toimisto (SRV)<\/strong> &#8211;\u00a0<span style=\"font-size: 1.2rem;\">toimiston erikoiskalusteet, lokerikot, naulakot, keitti\u00f6t <a href=\"https:\/\/merianto.com\/fi\/portfolio\/woodcity-toimisto-2\/\">(gallery)<\/a><\/span><\/p><p><strong>Katajanokan Laituri (Haahtela)<\/strong> &#8211; erikoiskalusteet, sein\u00e4verhoilu, naulakot-lokerikot, keitti\u00f6t <a href=\"https:\/\/merianto.com\/fi\/portfolio\/noli-tjk-herttoniemi-2\/\">(gallery)<\/a><\/p><p><strong>Ilmalan Aura (Hartela)<\/strong> &#8211; toimistotalon erikoiskalusteet, tiskit, keitti\u00f6t, naulakot-lokerikot, allaskalusteet <a href=\"https:\/\/merianto.com\/fi\/portfolio\/mevet-elainsairaala-2\/\">(gallery)<\/a><\/p><p><strong>Finlandia Talo (Skanska)<\/strong> &#8211; Finlandia Talon erikoiskalusteet, sisustuselementid, sein\u00e4verhoukset, vanhojen huonekalujen entis\u00f6inti <a href=\"https:\/\/merianto.com\/fi\/portfolio\/finlandia_talo\/\">(gallery)<\/a><\/p><p><strong>Lyyra (Haahtela)<\/strong> &#8211; Lobby alueen erikoiskalusteet <a href=\"https:\/\/merianto.com\/fi\/portfolio\/lyyra\/\">(gallery)<\/a><\/p><p><strong>Renalis Lasnam\u00e4e dialyysiklinikka<\/strong> &#8211; tiskit, naulakot, keitti\u00f6t, erikoiskalusteet\u00a0<\/p><p><strong>Medicum Stockmann<\/strong> &#8211; terveyskeskuksen erikoiskalusteet, tiskit, naulakot, keitti\u00f6t ja erikoiskalusteet <a href=\"https:\/\/merianto.com\/fi\/portfolio\/medicum\/\">(gallery)<\/a><\/p><p><strong>Hoplaxskolan Helsinki<\/strong> (Lujatalo) &#8211; koulun sis\u00e4ovien toimitus<\/p><p><strong>Konepajan Lukio (NCC)<\/strong> &#8211; koulun vaatekalusteet, naulakot, varastohyllyt ja keitti\u00f6kalusteet<\/p><p><strong>Kanniston Koulu (YIT)<\/strong> &#8211; koulun sis\u00e4ovien toimitus<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9843\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-9843\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2023<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9843\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-9843\"><p><strong> Mevet El\u00e4insairaala (Consti) <\/strong><strong>\u2013 el\u00e4inklinikan erikoiskalusteet, <\/strong>Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/mevet-elainsairaala\/\">(galleria)<\/a><\/p><p><strong>Pohjois-Porin Monitoimitalo (Skanska) <\/strong><strong>\u2013<\/strong> RST kalusteet, hyllyt, p\u00f6yd\u00e4t, Pori<\/p><p><strong>NOLI Herttoniemi \u2013 <\/strong>hotelin lobby`n kalusteet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/noli-tjk-herttoniemi\/\">(galleria)<\/a><\/p><p><strong>Pohjois-Viron L\u00e4\u00e4ketieteellinen Keskus (MERKO) \u2013 <\/strong>rakennusvaihe III, sairaalan erikoiskalusteet<\/p><p><strong>Runosm\u00e4en monitoimitalo (NCC) \u2013 <\/strong>Kulttuuri- ja koulutustalon kirkko- ja kappelisalin erikoiskalusteet, Turku<\/p><p><strong>Helsingin Ensikoti (Consti) \u2013 <\/strong>Hooldekodu erim\u00f6\u00f6bel, Helsingi<\/p><p><strong>Tarton yliopistollinen sairaala &#8211; <\/strong>C, M ja G1-rakennusten erikoiskalusteet, keitti\u00f6t, Tartu <a href=\"http:\/\/merianto.com\/fi\/portfolio\/tartu-university-hospital-m-and-c-corps\/\">(galleria)<\/a><\/p><p><strong>Boost C5 (NCC)<\/strong> &#8211; toimistotalon sis\u00e4ovet, viilupintainen sein\u00e4verhoilu, keitti\u00f6- ja naulakkokalusteet, Helsinki<\/p><p><strong>Metacore Games (FYRA) &#8211; toimiston erikoiskalusteet, H<\/strong>elsinki<\/p><p><strong>Hotelli Omenatarha Kisakallio (Readcon)<\/strong> &#8211; hotelin erikoiskalusteet, huonekalusteet, Lohja <a href=\"http:\/\/merianto.com\/fi\/portfolio\/hotelli-omenatarha-kisakallio\/\">(galleria)<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9844\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-9844\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2022<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9844\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-9844\"><p><strong>Solo Sokos Hotel Torni (Sokotel\/Haahtela) <\/strong><strong>\u2013 <\/strong>hotellihuoneet, ravintolakalusteet ja SPA, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/solo-sokos-hotel-torni\/\">(galleria)<\/a><\/p><p><strong>Tanssin Talo Kaapelitehtaalla (Haahtela) <\/strong><strong>\u2013<\/strong> erikoiskalusteet, tiskit, keitti\u00f6t, Helsinki<\/p><p><strong>Open Innovation House (SRV) <\/strong><strong>\u2013<\/strong> vaate- ja neuvottelutilojen kalusteet, Helsinki<\/p><p><strong>Bulevardin toimisto (Haahtela) &#8211;<\/strong>Toimiston akustiset sein\u00e4paneelit, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/bulevardin-toimisto\/\">(galleria)<\/a><\/p><p><strong>Hatsinanpuisto Ab Kiinteist\u00f6 Oy (NCC) <\/strong><strong>\u2013<\/strong> toimistotalon keitti\u00f6t, Helsinki<\/p><p><strong>N\u00f5mme Tervisekeskus <\/strong><strong>\u2013<\/strong> terveyskeskuksen erikoiskalusteet, Tallinna<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9845\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-9845\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2021<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9845\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-9845\"><p><strong>Urhea-halli (Indepro) <\/strong><strong>\u2013<\/strong> urheahallin erikoisjalusteet, tiskit, vaatekalusteet, Helsinki<\/p><p><strong>Estonian Ebmassy in Ottawa<\/strong><strong>\u2013 <\/strong>Viron Suurl\u00e4hetyst\u00f6 kanadassa, erikoiskalusteet, Ottawa<\/p><p><strong>Roukon Yhten\u00e4iskoulu (YIT) <\/strong><strong>\u2013<\/strong>koulun erikoiskalusteet, naulakot, keitti\u00f6t, v\u00e4lisein\u00e4t, allaskalusteet, Valkeakoski<\/p><p><strong>Valteri-koulu Ruskis (NCC) <\/strong><strong>\u2013 <\/strong>koulun erikoiskalusteet, keitti\u00f6t, RST kalusteet, Helsinki<\/p><p><strong>Juslenia Turku (Skanska) <\/strong><strong>\u2013 <\/strong>erikoiskalusteet, naulakot, sein\u00e4panelit, vitriinit, Turku<\/p><p><strong>K-Group peakontori laiendus (Haahtela) \u2013 <\/strong>erikoiskalusteet, viilu ja laminaattisein\u00e4t, keitti\u00e4t, WC kalusteet naulakot, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/kalasataman-kampus\/\">(galleria)<\/a><\/p><p><strong>Lepp\u00e4vaaran Monikko (SRV) \u2013 <\/strong>koulun erikoiskalusteet, keitti\u00f6t, naulakot, varastot, jne, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/leppavaaran-monikko\/\">(galleria)<\/a><\/p><p><strong>KELA Pit\u00e4j\u00e4nm\u00e4ki (YIT) \u2013<\/strong>keitti\u00f6t, naulakot, allaskalusteet, Helsinki<\/p><p><strong>YLE l\u00e4hetyskeskus (R4) \u2013 <\/strong>erikoiskalusteet, laitep\u00f6yd\u00e4t, sis\u00e4ovet, Helsinki<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9846\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-9846\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2020<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9846\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-9846\"><p><strong>Rantatien Loikka (Skanska) <\/strong><strong>\u2013<\/strong>toimistotalon erikoiskalusteet, WC keitti\u00f6t, allastasot, Helsinki<\/p><p><strong>Olympiastadion (Skanska) <\/strong><strong>\u2013 <\/strong>WC jakosein\u00e4t, vastaanottotiskit, erikoiskalusteet, komposiittitasot, Helsinki<\/p><p><strong>Vallila Folks Hotel <\/strong><strong>\u2013 <\/strong>hotellin kalusteet, huoneet ja ravintolat, erikoiskalusteet, Helsinki<\/p><p><strong>Pelgulinna S\u00fcnnitusmaja (Vanalinna Ehitus) <\/strong><strong>\u2013 <\/strong>Pelgulinna naistenklinikan potilaspanelit, erikoiskalusteet, keitti\u00f6t, Tallinna<\/p><p><strong>Soljan Lastentalo (Pallas) <\/strong><strong>\u2013 <\/strong>erikoiskalusteet, naulakot, keitti\u00f6t, v\u00e4lisein\u00e4t, allaskalusteet, Pirkkala<\/p><p><strong>Estonian Embassy in Rome (ARS Projekt) <\/strong><strong>\u2013<\/strong>Viron Suurl\u00e4hetyst\u00f6 Italiassa, erikoiskalusteet, Rooma <a href=\"http:\/\/merianto.com\/fi\/portfolio\/viron-suurlahetysto-roomassa\/\">(galleria)<\/a><\/p><p><strong>Etera-talo, Aava (YIT) <\/strong><strong>\u2013 <\/strong>toimistotalon erikoiskalusteet, sis\u00e4ovet, Helsinki<\/p><p><strong>HML Toimistotalo (Jatke) <\/strong><strong>\u2013 <\/strong>toimistotalon erikoiskalusteet, sermit, H\u00e4meenlinna<\/p><p><strong>Warner Music Tallinn \u2013 <\/strong>toimiston erikoiskalusteet<\/p><p><strong>Koy Keilalampi (YIT) \u2013 <\/strong>toimistotalon erikoiskalusteet, keitti\u00f6t, naulakot, Helsinki<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9847\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-9847\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2019<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9847\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-9847\"><p><strong>Messuhotelli (YIT) \u2013 <\/strong>erikoiskalusteet, sein\u00e4verhoukset, tiskit, ravintola ja WC kalusteet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/holiday-inn-helsinki-expo\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>K-Group peakontor (Haahtela) \u2013<\/strong>erikoiskalusteet, viilu ja laminaattisein\u00e4t, keitti\u00e4t, WC kalusteet naulakot, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/kalasataman-kampus\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Otaniemen Koulu (YIT) \u2013<\/strong>koulun erikoiskalusteet, naulakot, keitti\u00f6t, allaskalusteet, Espoo<\/p><p><strong>TRIPLA keskus (YIT) \u2013<\/strong>keskuksen erikoiskalusteet, ravintolat, sein\u00e4verhoukset, toimistotilojen erikoiskalusteet, Helsinki<\/p><p><strong>Postimees Grupp \u2013 <\/strong>toimistotalon erikoiskalusteet, keitti\u00f6t, studiot ja tiskit, Tallinna<\/p><p><strong>Jorvin Saraala (Rakennuspartio) \u2013 <\/strong>sairaalan RST kalusteet, l\u00e4piantokaapit, hyllyt, Helsinki<\/p><p><strong>Rajatorpantie 8 (Consti) <\/strong>\u2013 toimistotalon WC tilojen corian-allaskalusteet, Vantaa<\/p><p><strong>Leip\u00e4tehdas (NHK) <\/strong>\u2013 erikosikalusteet, kavilan tiski, Helsinki<\/p><p><strong>ITIS Cinema (Skanska) <\/strong>\u2013 corian allaskalusteet ja kaapit, Helsinki<\/p><p><strong>Tartu \u00dclikooli \u00fcli\u00f5pilaskodu <\/strong>\u2013 kampuksen 75 tilan huonekalusteet, Tartu<\/p><p><strong>Universal Music Finland <\/strong>\u2013 toimiston erikoiskalusteet, keitti\u00f6t, sofat, allaskalusteet, Helsinki<\/p><p><strong>L\u00e4\u00e4ne-Tallinna Keskhaigla<\/strong> \u2013 sairaalan l\u00e4\u00e4kekalusteet, keitti\u00f6st, Tallinna<\/p><p><strong>Mikkelin Keskussairaala<\/strong> \u2013 sairaalan l\u00e4\u00e4kekalusteet, Mikkeli<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9848\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-9848\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2018<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9848\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-9848\"><p><strong>Amos Rex museo (Haahtela) <\/strong>\u2013 erikoiskalusteet, keitti\u00f6t, komposiittitasot, Helsinki <strong><a href=\"http:\/\/merianto.com\/fi\/portfolio\/amos-rex-taidemuseo\/\">(galleria)<\/a><\/strong><\/p><p><strong>REDI keskus \u2013 <\/strong>corianallastasot, WC jakosein\u00e4t, sein\u00e4verhoilut, Helsinki<\/p><p><strong>Metrolia Koulutuskeskus (YIT) \u2013 <\/strong>opetuskeskuksen keitti\u00f6t, komposiittitasot, ravintolakalusteet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/metropolia-koulutuskeskus\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>NCC toimistotalo (NCC) \u2013 <\/strong>m\u00fc\u00fcgisalongi sisustus, Helsinki<a href=\"http:\/\/merianto.com\/fi\/portfolio\/ncc-toimistotalo\/\"><strong> (galleria)<\/strong><\/a><\/p><p><strong>W\u00e4rtsil\u00e4 Helsinki Campus (Consti)<\/strong> \u2013 toimistotalon erikoiskalusteet, kivitasot, Helsinki<\/p><p><strong>Maakri talo (Merko) \u2013 <\/strong>toimistotalon hissiaulat 1-30krs, viiluverhoukset ja erikoiskalusteet, Tallinna <a href=\"http:\/\/merianto.com\/fi\/portfolio\/maakri-talo\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Korkeavuorenkatu 10 (NHK) \u2013 <\/strong>erikoiskalusteet, keitti\u00f6t, ikkunapenkit, Helsinki<\/p><p><strong>Os<\/strong><strong>tokeskus P\u00e4rnu mnt 22 (Merko) \u2013 <\/strong>sein\u00e4verhoilu ja lasisein\u00e4t, Tallinna<\/p><p><strong>S<\/strong><strong>tockmann Ravintolat (Royal Ravintolat) \u2013 <\/strong>ravintolakalusteet, Helsinki<\/p><p><strong>Talma Golf \u2013 <\/strong>ravintolakalusteet, Talma<\/p><p><strong>Sakkaroosi Tiilitalo (NHK)<\/strong> \u2013 keitti\u00f6kalusteet, Helsinki<\/p><p><strong>M<\/strong><strong>aistraatinportti 2 (FIRA) \u2013<\/strong>toimistitalon erikoiskalusteet, pukukaapit, allastasot, Helsinki<\/p><p><strong>\u00d6piku Toimistotalo (Merko) \u2013<\/strong>toimistotalon sein\u00e4verhoukset, Tallinna <a href=\"http:\/\/merianto.com\/fi\/portfolio\/opiku-toimistotalo\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Tampereen Yliopistollinen sairaala, D-siipi <\/strong><strong>(SRV) \u2013 <\/strong>sairaalan erikoiskalusteet, l\u00e4\u00e4kekaapit, tiskit, keitti\u00f6t, Tampere <a href=\"http:\/\/merianto.com\/fi\/portfolio\/tampereen-yliopistollinen-sairaala-tays\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>S<\/strong><strong>akkaroosi Tiilitalo (Nurminen Works) \u2013<\/strong>keitti\u00f6kalusteet, Helsinki<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9849\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-9849\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2017<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9849\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-9849\"><p><strong>Palace Royal Ravintolat (Skanska)<\/strong> \u2013 tiskit, sein\u00e4paneelit, garderobit, komposiittitasot, keitti\u00f6t, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/palace-royal-ravintolat\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Fastighets Ab Glaspalatset i Helsinfors(Lasipalatsi)<\/strong> \u2013 toimistojen erikoiskalusteet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/fastighets-ab-glaspalatset-i-helsingfors-lasipalatsi-helsinki\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Lasipalatsi (Haahtela) <\/strong>\u2013 toimiston erikoiskalusteet, Helsinki<\/p><p><strong>Hermannin Rantatie (YIT) <\/strong>\u2013 toimistotalon erikoiskalusteet, keitti\u00f6t, allaskalusteet, ravintola, Helsinki<\/p><p><strong>V\u00e4\u00e4ksyntie toimistotalo <\/strong>\u2013 toimiston erikoiskalusteet, keitti\u00f6t, ikkunapenkit, naulakot, tiskit, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/vaaksyntie-toimistotalo\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Exel<\/strong> <strong>(E-Sports Group Oy) <\/strong>\u2013 urheilutarvikkeiden ja vaatetus showroomin kalusteet, korokkeet, st\u00e4ndit, sein\u00e4paneelit, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/exel-esittelytila\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Tallinnan Naistenklinikka<\/strong> \u2013 l\u00e4\u00e4kekaapit ja l\u00e4piantokaapit<\/p><p><strong>Handelsbanken Helsinki (NCC) <\/strong>\u2013 keitti\u00f6t, naulakot-lokerikot, tiskit, sohvakalusteet <a href=\"http:\/\/merianto.com\/fi\/portfolio\/handelsbanken-helsinki\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Vantaan Energia (Fira)<\/strong>\u2013 kokolasisein\u00e4t ja viilupintaiset v\u00e4liovet, Vantaa <strong>(galleria) <\/strong><a href=\"http:\/\/merianto.com\/fi\/portfolio\/vantaan-energia\/\">Vantaan Energia<\/a><\/p><p><strong>Fresenius <\/strong>\u2013 l\u00e4\u00e4kekeskuksen erikoiskalusteet, Tallinna<\/p><p><strong>HARTELA toimistotalo<\/strong> (Ruutupuu) \u2013 toimistotalon erikoiskalusteet, keitti\u00f6t, naulakot, Helsinki<\/p><p><strong>Plastic Surgery Center Helsinki<\/strong> \u2013 asiv\u00e4lisein\u00e4t ja ovet, Helsinki<\/p><p><strong>Smartly.io<\/strong>\u2013 toimiston erikoiskalusteet, naulakkokalusteet, sein\u00e4paneelit, pengit, stage, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/smartly-io\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Pasilanportti, Fennia (Fira) <\/strong>\u2013 toimistotalon aulan viiluverhoukset ja massiivipuuverhoukset, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/fennia-pasilanportti\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Sandro Tapiola, Tuulikinsillan paviljonki <\/strong>\u2013 ravintolan kalusteet, p\u00f6yd\u00e4t, tiskit, Espoo<\/p><p><strong>Nurmij\u00e4rven Monitoimitalo (Skanska) <\/strong>\u2013 monitoimitalon akustiikkapaneelit ja viilupintaiset sein\u00e4verhoukse <a href=\"http:\/\/merianto.com\/fi\/portfolio\/nurmijarven-monikko\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Port of Helsinki, MT2 (YIT) <\/strong>\u2013 terminaalit kalusteet, tiskit, penkit, WC kalusteet ja v\u00e4lisein\u00e4t <a href=\"http:\/\/merianto.com\/fi\/portfolio\/lansiterminaali-2\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Hanasaaren kultturikeskus<\/strong> \u2013 WC kalusteet ja jakov\u00e4lisein\u00e4t, corian \u2013 allastasot, ikkunapenkit ja kotelot <a href=\"http:\/\/merianto.com\/fi\/portfolio\/hanasaare-kulttuurikeskus\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>SA Elva Kultuurikeskus <\/strong>\u2013 kulttuurikeskuksen erikoiskalusteet, verhot, Elva\/Viro<\/p><p><strong>Iso Omena keskus<\/strong> \u2013 allaskaapit, corian \u2013 tasot, keitti\u00f6t, varastotilojen kalusteet, Helsinki<\/p><p><strong>Estonian National Museum<\/strong> \u2013 fotosein\u00e4-syclorama, Tartu\/Estonia<\/p><p><strong>TREDU, Avoniikka lennonopetus<\/strong> \u2013 keitti\u00f6t, RST kalusteet, asiakastiski, naulakot, Tampere<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98410\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-98410\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2016<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98410\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-98410\"><p><strong>KOY Sipoon PT-Logistiikkakeskus (Freeway)<\/strong> \u2013 keitti\u00f6kalusteet, ravintolatiskit, allaskalusteet, Sipoo<\/p><p><strong>Auroran koulu (NCC)<\/strong> \u2013 lasiv\u00e4lisein\u00e4t ja ovet, massiivipuurakenteet, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/auroran-koulu\/\">(galleria)<\/a><\/p><p><strong>Svenska Normallyceum (NCC)<\/strong> \u2013 lasiv\u00e4lisein\u00e4t ja erikoiskalusteet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/svenska-normallyceum-helsinki\/\">(galleria)<\/a><\/p><p><strong>AITIO Business Park Verdi (NCC)<\/strong> \u2013 allaskalusteet, aulan ter\u00e4ssein\u00e4verhoilu, Helsinki<\/p><p><strong>Clarion Hotel Helsinki (HENT)<\/strong> \u2013 erikoiskalusteet, vastaanotto- ja baaritiskit <a href=\"http:\/\/merianto.com\/fi\/portfolio\/clarion-hotel-helsinki\/\">(galleria)<\/a><\/p><p><strong>Turun Normaalikoulu (Skanska)<\/strong> \u2013 lasiv\u00e4lisein\u00e4t, Turku<\/p><p><strong>Tampereen kansanv\u00e4linen koulu (SRV)<\/strong> \u2013 A osa, koulun erikoiskalusteet, keitti\u00f6t, lasisein\u00e4t, ovet, Tampere <a href=\"http:\/\/merianto.com\/fi\/portfolio\/tampereen-kansanvalinen-koulu\/\">(galleria)<\/a><\/p><p><strong>AALTO Kampuskirjasto (NCC)<\/strong> \u2013 erikoiskalusteet, vitriinit, keitti\u00f6t, naulakot, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/aalto-kampuskirjasto\/\">(galleria)<\/a><\/p><p><strong>Tuomelan Koulu (LUJATALO)<\/strong> \u2013 KOTA penkkikalusteet, H\u00e4meenlinna <a href=\"http:\/\/merianto.com\/fi\/portfolio\/tuomelan-koulu\/\">(galleria)<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98411\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-98411\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2015<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98411\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-98411\"><p><strong>Valteri-koulu, Onerva (SRV)<\/strong>\u2013 koulukalusteet, tiskit, keitti\u00f6t, vitriinit, erikoiskalusteet, Jyv\u00e4skyl\u00e4 <a href=\"http:\/\/merianto.com\/fi\/portfolio\/valteri-koulu-onerva-jyvaskyla\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Kansalliskirjasto<\/strong>\u2013 kirjaston erikoiskalusteet, vitriinit, lokerokaapit, tiskit, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/kansalliskirjastoon\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>HUS Sy\u00f6patautien klinikka<\/strong>\u2013 sairaalan kalusteet, tiskit, Helsinki<\/p><p><strong>Koy Alberga D talo (NCC)<\/strong>\u2013 aulan erikoissisustus, allastasot ja kaapit, Helsinki<\/p><p><strong>Scandic Oscar (Vallila Contract)<\/strong>\u2013 hotellikalusteet, p\u00f6yd\u00e4t, kaapit, corian-allastasot, Varkaus<\/p><p><strong>Etera toimitalo (Lemmink\u00e4inen)<\/strong>\u2013 ikkunapenkkien kunnostus, erikoiskalusteet, corian-allastasot, keitti\u00f6t, Helsinki<\/p><p><strong>Tikkurilan Asemakeskus (YIT) <\/strong>\u2013 palvelutiskit, Vantaa <strong><a title=\"Luontokeskus Haltia (YIT) \u2013 luontokeskuksen kalusteet, tiskit, keitti\u00f6t ja betoniallastasot\" href=\"http:\/\/www.merianto.com\/luontokeskus-haltia-yit-looduskeskuse-erimoobel-letid-koogid-ja-kivipinnad\/\"><br \/><\/a><\/strong><\/p><p><strong>Hotel Indigo, Bulevardi 26 (NCC\/Restel)<\/strong>\u2013 hotelin erikoiskalusteet, ravintolakalusteet, baaritiskit, penkit, porraskaiteet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/hotel-indigo-bulevardi-helsinki\/\"><strong>(galleria)<\/strong><\/a><a title=\"Helsingin Yliopisto, Unioninkatu 35\" href=\"http:\/\/www.merianto.com\/fi\/referenssit\/helsingin-yliopisto-unioninkatu-35\/\"><strong><br \/><\/strong><\/a><\/p><p><strong>Terveyden ja hyvinvoinnin laitos (NCC)<\/strong>\u2013 ravintolakalusteet, WC kalusteet, tiskit, taulut, AV-kalusteet, naulakot, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/terveyden-ja-hyvinvoinnin-laitos-thl\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Hirvikosken koulu (NCC)<\/strong> \u2013 koulukalusteet, keitti\u00f6t, naulakot, varastotilojen kalusteet, Loimaa <a href=\"http:\/\/merianto.com\/fi\/portfolio\/hirvikosken-koulu\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>HUSLAB (SRV)<\/strong>\u2013 keitti\u00f6kalusteet, naulakot, lokerikot, kaapistot, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/huslab-helsingin-yliopistokiinteistot\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Rajam\u00e4en Uimahalli (Fira Oy)<\/strong> \u2013 RST kalusteet, tiski, keitti\u00f6t, erikoiskalusteet, Rajam\u00e4ki<\/p><p><strong>Finnish International School of Tampere (SRV)<\/strong> \u2013 kooli erim\u00f6\u00f6bel, uksed, klaasseinad, Tampere<\/p><p><strong>Datacity Turku (NCC)<\/strong> \u2013 toimiston erikoiskalusteet, naulakot, Turku<\/p><p><strong>Koy Estradi (FIRA)<\/strong> \u2013 toimiston lasisein\u00e4t ja ovet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/kiinteisto-oy-estradi\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Suomen Farmaatsialiitto<\/strong> \u2013 neuvottelutilan kalusteet, Helsinki<\/p><p><strong>Helsingin p\u00e4\u00e4rautatieasema<\/strong> \u2013 WC sisustus, Helsinki<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98412\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-98412\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2014<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98412\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-98412\"><p><strong>Malmin sairaala (YIT)<\/strong>\u2013 erikoiskalusteet, tiskit, metallikalusteet, pukukaapit, potilaskalusteet jne, Helsinki <strong><a href=\"http:\/\/merianto.com\/fi\/portfolio\/malmin-sairaala\/\">(galleria)<\/a> <a title=\"Luontokeskus Haltia (YIT) \u2013 luontokeskuksen kalusteet, tiskit, keitti\u00f6t ja betoniallastasot\" href=\"http:\/\/www.merianto.com\/luontokeskus-haltia-yit-looduskeskuse-erimoobel-letid-koogid-ja-kivipinnad\/\"><br \/><\/a><\/strong><\/p><p><strong>Helsingin Yliopisto, Unioninkatu 35 (Lemmink\u00e4inen)<\/strong>\u2013 keitti\u00f6t, metalli-lasisein\u00e4t, ovet, auditorion penkit, sein\u00e4verhoilu, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/helsingin-unioninkatu-yliopistu\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Siuntion kylpyl\u00e4 (Vallila) <\/strong>\u2013 komposiittipenkit ja naulakot, Siuntio<\/p><p><strong>North Estonian Medical Center (Merko)<\/strong> \u2013 corian-vastaanottotiskit, lasisein\u00e4t, keitti\u00f6t, infotaulut, Tallinna<\/p><p><strong>Embassy of Estonia in China<\/strong> (V\u00e4lisministeerium) \u2013 nojatuolit, kalusteet, verhot, Beijing <a href=\"http:\/\/merianto.com\/fi\/portfolio\/viron-suurlahetysto-pekingissa\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>ELY keskus (UH Rakennus)<\/strong> \u2013 toimiston lasisein\u00e4t ja kalusteet, Helsinki<\/p><p><strong>North Estonian Medical Center<\/strong> \u2013 corian-vastaanottotiskit, lasisein\u00e4t, keitti\u00f6t, infotaulut, Tallinna <a title=\"North Estonian Medical Center\" href=\"http:\/\/www.merianto.com\/tehtud-tood\/pohja-eesti-regionaalhaigla\/\"><br \/><\/a><\/p><p><strong>Orion tehdas<\/strong>\u2013 allasp\u00f6yd\u00e4t, kaapit, Espoo<\/p><p><strong>Karakallion koulu (NCC)<\/strong> \u2013 auditorion akustiikkapaneelit, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/karakallion-koulu\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Helsingin Rautatieasema<\/strong> <strong>(UH Rakennus) <\/strong>\u2013 keitti\u00f6t, erikoiskalusteet, Helsinki<\/p><p><strong>Brondankulma ravintola<\/strong> \u2013 ravintolan metallirakenteet, kivitasot, kivialtaat, viinikaappi, erikoiskalusteet, Helsinki <strong>(galleria)<\/strong><\/p><p><strong>Tallinna Piiskoplik Toomkirik<\/strong> \u2013 infotiski <a href=\"http:\/\/merianto.com\/fi\/portfolio\/tallinnan-piispallinen-tuomiokirkko\/\"><strong>(galleria)<\/strong><\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98413\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-98413\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2013<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98413\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-98413\"><p><strong>Luontokeskus Haltia (YIT)<\/strong>\u2013 luontokeskuksen kalusteet, tiskit, keitti\u00f6t ja betoniallastasot, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/suomen-luontokeskus-haltia\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Koulutuskeskus Tavastia (Lujatalo Oy)<\/strong>\u2013 erikoiskalusteet, keitti\u00f6t, vitriinit, tiskit ja vaatekaapit, H\u00e4meenlinna<\/p><p><strong>Lampan Talo (NCC Rakennus Oy)<\/strong>\u2013 erikoiskalusteet, allastasot, sein\u00e4paneelit, Helsingi<\/p><p><strong>Hotel Cumulus H\u00e4meenpuisto (Vallila Interior Oy)<\/strong>\u2013 hotellihuoneiden kalusteet ja sein\u00e4paneelit, Tampere<\/p><p><strong>Koy Alberga C talo (NCC)<\/strong>\u2013 valoaulan kalusteet, buffet, lasipaneelit, viiluverhoilu, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/alberga-c-talo\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Vantaan Energia j\u00e4tevoimalaitos<\/strong>\u2013 lasiv\u00e4lisein\u00e4t, peilit ja suihkusein\u00e4t, Vantaa<\/p><p><strong>Nordea, AKK7 <\/strong>(FIRA Oy) \u2013 keitti\u00f6t, naulakot, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/nordea-akk7-toimisto\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Wanha Mestari Pub Lahti<\/strong> (Vallila Interior Oy) \u2013 baarin erikoiskalusteet, sohvat, Lahti<\/p><p><strong>Lahden Seurahuone<\/strong> (H\u00e4meenmaan Kiinteist\u00f6t) \u2013 vaatetilojen kalusteet, Lahti<\/p><p><strong>Helsingin Yliopisto<\/strong> (NCC) \u2013 keitti\u00f6kalusteet ja Durat-allaskalusteet, Helsinki<\/p><p><strong>KOY T\u00f6\u00f6l\u00f6nlahden Toimistotalo<\/strong> (Lemmink\u00e4inen) \u2013 v\u00e4lisein\u00e4t ja ovet, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/toolonlahden-toimistotalo\/\"><strong>(galleria) <\/strong><\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98414\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-98414\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2012<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98414\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-98414\"><p><strong>Haukilahden Vesitorni (Skanska Infra) <\/strong>\u2013 ravintolan erikoiskalusteet, corian-allastasot ja ikkunapenkit, Espoo <a href=\"http:\/\/merianto.com\/fi\/portfolio\/haukilahden-vesitorni\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Nikinm\u00e4en P\u00e4iv\u00e4koti<\/strong>(Ulf Friberg Oy) \u2013 p\u00e4iv\u00e4kodin kalusteet ja lasisein\u00e4t, Vantaa<\/p><p><strong>Senaatti-Kiinteist\u00f6t, Ratapihantie 9<\/strong>(Reno Rakennus) \u2013 keitti\u00f6t, tiskit, istuntosalit, Helsinki<\/p><p><strong>Hyvink\u00e4\u00e4n Virastotalo<\/strong>(Rakennus Antti J. Ahola) \u2013 istuntosalien kalusteet, Hyvink\u00e4\u00e4 <a href=\"http:\/\/merianto.com\/fi\/portfolio\/hyvinkaan-virastotalo\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Kaunialan Sairaala, R-osasto<\/strong>(Rakennustuote) &#8211; sairaalan kalusteet, keitti\u00f6t ja sauna, Kauniainen<\/p><p><strong>Businesspark Triotto toimistotalo<\/strong> (YIT) \u2013 toimistotalon keitti\u00f6t, corian-tiskit, suihkusein\u00e4t ja sauna, Helsinki <strong><a href=\"http:\/\/merianto.com\/fi\/portfolio\/toimistotalo-triotto\/\">(galleria)<\/a> <a title=\"Triotto\/DNA (YIT), keitti\u00f6kalusteet, vastaanottotiskit, sauna\" href=\"http:\/\/www.merianto.com\/tehtud-tood\/triottodna-yit-keittiokalusteet-vastaanottotiskit-sauna\/\"><br \/><\/a><\/strong><\/p><p><strong>Stora Enso office<\/strong>(Lemmink\u00e4inen) \u2013 lasisein\u00e4t, Helsinki<\/p><p><strong>Helsingin Observatorio<\/strong>(NCC) \u2013 vanhojen kalusteiden kunnostus, erikoiskalusteet ja ravintola, Helsinki<\/p><p><strong>International School of Helsinki<\/strong>\u2013 pukukaapit, keitti\u00f6kalusteet, Helsinki<\/p><p><strong>Harjunrinteen Koulu<\/strong> (Lujatalo OY) \u2013 koulukalusteet, Riihim\u00e4ki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/harjunrinteen-koulu\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>FINAVIA<\/strong>(Ruutupuu Oy) \u2013 lentoaseman portit-tiskit, Vantaa<\/p><p><strong>Porolahden Koulu<\/strong> (Reno-Rakennus) \u2013 koulukalusteet, lasisein\u00e4t ja ovet, Helsinki<\/p><p><strong>Koy Alberga B <\/strong>(NCC) \u2013 toimistotalon keitti\u00f6kalusteet, Espoo<b><\/b><\/p><p><strong>Vind\u00e4ngens skola och daghem (<\/strong>NCC) \u2013 koulukalusteet, Espoo<\/p><p><strong>Paasitorni Hoteli<\/strong>(Skanska) \u2013 puulasisein\u00e4t ja ovet, Helsinki<\/p><p><strong>Kinaporin vanhusten palvelutalo<\/strong>(Lujatalo) \u2013 keitti\u00f6t, tiskit ja erikoiskalusteet, Helsinki<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98415\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-98415\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2011<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98415\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-98415\"><p><strong>Finlandia Talo<\/strong> (YIT) \u2013 ravintolakalusteet ja marmoritasot, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/finlandia-talo-ravintola\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Viikin Ymp\u00e4rist\u00f6talo<\/strong> (Lemmink\u00e4inen) \u2013 sis\u00e4lasisein\u00e4t, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/viikin-ymparistotalo\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Kuntolan koulu<\/strong> (YIT) \u2013 koulukalusteet, sis\u00e4lasisein\u00e4t, ikkunapenkit, J\u00e4rvenp\u00e4\u00e4 <a href=\"http:\/\/merianto.com\/fi\/portfolio\/kuntolan-koulu\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>Kanniston koulu<\/strong> (YIT) \u2013 sis\u00e4ovet ja ikkunat, Vantaa <a href=\"http:\/\/merianto.com\/fi\/portfolio\/kanniston-koulu\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>J\u00e4tk\u00e4saaren Pelastusasema<\/strong> (LTR) \u2013 erikoiskalusteet, sermit, Helsinki<\/p><p><strong>Heltech Haaga<\/strong> (NCC) \u2013 koulutuskeskuksen keitti\u00f6t, Helsinki<\/p><p><strong>Saamelaiskulttuurikeskus Sajos<\/strong> (KSBR) \u2013 erikoiskalusteet ja lasisein\u00e4t\/ovet, Inari<\/p><p><strong>Sipoon Logistiikkakeskus <\/strong>(Lemmink\u00e4inen) \u2013 keitti\u00f6kalusteet, Kerava<\/p><p><strong>Miilin P\u00e4iv\u00e4koti <\/strong>(Ulf Friberg Oy) \u2013 p\u00e4iv\u00e4kodin kalusteet ja metallirakenteet, S\u00f6derkulla <a href=\"http:\/\/merianto.com\/fi\/portfolio\/paivakoti-miili\/\"><strong>(galleria)<\/strong><\/a><\/p><p><strong>J\u00e4tk\u00e4saaren Pacific <\/strong>(Hartela) \u2013 erikoiskalusteet, Helsinki<\/p><p><strong>Wanha Villatehdas<\/strong> (SRV) \u2013 kalusteet, keitti\u00f6t, WC-sein\u00e4t ja corian-allastasot, Hyvink\u00e4\u00e4 <a href=\"http:\/\/merianto.com\/fi\/portfolio\/wanha-villatehdas-kahvila\/\"><strong>(galleria)<\/strong><\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98416\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-98416\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2010<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98416\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-98416\"><p><strong>Suomen Kansallisooppera<\/strong> (KT Interior) \u2013 erikoiskalusteet, Helsinki<\/p><p><strong>Helsingin Lastenklinikka<\/strong> (YIT) \u2013 sairaalan erikoiskalusteet, Helsinki<\/p><p><strong>Vanttilan P\u00e4iv\u00e4koti<\/strong> (NCC) \u2013 erikoiskalusteet, ikkunapenkit, Helsinki<\/p><p><strong>Karamalmens skola<\/strong> (NCC) \u2013 koulukalusteet, Helsinki<\/p><p><strong>Suomen El\u00e4inl\u00e4\u00e4k\u00e4riliitto<\/strong> (Studio Bergroth) \u2013 toimistokalusteet, Helsinki<\/p><p><strong>Polaris Business Park<\/strong> Talo 7 (Lemmink\u00e4inen\/NCC) \u2013 asisein\u00e4t-sein\u00e4verhoilut, keitti\u00f6t<\/p><p><strong>Tapiola-Ryhm\u00e4 PK2 (YIT Rakennus OY) <\/strong>\u2013 k\u00e4yt\u00e4vien puulasisein\u00e4t ja ovet, Espoo<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98417\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-98417\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2009<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98417\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-98417\"><p><strong>Helsingin Salmisaarentalo, Hovioikeus (PEAB)<\/strong> \u2013 v\u00e4lisein\u00e4t ja ovet, Helsinki<\/p><p><strong>Tilkan Viuhka (Palmberg)<\/strong> \u2013 toimistotalon keitti\u00f6t, naulakot, peilit, Helsinki<\/p><p><strong>North Estonian Medical Center<\/strong>(Koger &amp; Partnerid) \u2013 erikoiskalusteet ja vastaanottotiskit, Tallinna<\/p><p><strong>Gustav Paulig Kahvipaahtimo (Lemcon)<\/strong> \u2013 kahvipaahtimon kalusteet ja sein\u00e4verhoilut, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/gustav-paulig-kahvipaahtimo\/\">(galleria)<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98418\" class=\"elementor-tab-title\" data-tab=\"18\" role=\"button\" aria-controls=\"elementor-tab-content-98418\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2008<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98418\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"18\" role=\"region\" aria-labelledby=\"elementor-tab-title-98418\"><p><strong>Espoo Keskus Entresse<\/strong>\u2013 kirjaston tiskit ja kahvilan kalusteet, Espoo<\/p><p><strong>Vuosaari Satam (Lujatalo)<\/strong>\u2013 infotiskit, v\u00e4lisein\u00e4t, Helsinki <a href=\"http:\/\/merianto.com\/fi\/portfolio\/gatehouse-vuosaari\/\">(galleria)<\/a><\/p><p><strong>Polaris Business Park<\/strong>, Talo 5 (Palmberg\/NCC) \u2013 lasisein\u00e4t, sein\u00e4verhoilut, keitti\u00f6t, Espoo<\/p><p><strong>Auroran Sairaalan (KT Interior)<\/strong> \u2013 kalusteet, Helsinki<\/p><p><strong>Risteilyalus FREEWINDS<\/strong>, Curacao (I.S. M\u00e4kinen) \u2013 miehist\u00f6hytit 62 kpl<\/p><p><strong>Polaris Business Park<\/strong>, Talo 6 (Palmberg, NCC) \u2013 lasisein\u00e4t ja ovet, Espoo<\/p><p><strong>Delta Plaza <\/strong>(Merko) \u2013 toimistotalon lasisein\u00e4t, ovet ja kalusteet, Tallinna<\/p><p><strong>Viron Parlamentin kanslia<\/strong> (Restor) \u2013 lasisein\u00e4t ja ovet, Tallinna <a href=\"http:\/\/merianto.com\/fi\/portfolio\/riigikogun-kanslia\/\">(galleria)<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98419\" class=\"elementor-tab-title\" data-tab=\"19\" role=\"button\" aria-controls=\"elementor-tab-content-98419\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2007<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98419\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"19\" role=\"region\" aria-labelledby=\"elementor-tab-title-98419\"><p><strong>Malmin Terveyskeskus (KT Interior)<\/strong> \u2013 kiinto ja irtokalusteet, asiakastiskit, Helsinki<\/p><p><strong>Swissotel Tallinn<\/strong>\u2013 erikoiskalusteet, bankettialue, Tallinna<\/p><p><strong>Swissotel Tallinn<\/strong>\u2013 huoneiden kalusteet (237 huonetta), ravintolat, Tallinn (projektinjohto)<\/p><p><strong>S\u00f5pruse \u00c4rimaja<\/strong>(Merko)<b> <\/b>\u2013 lasisein\u00e4t, Tallinna<\/p><p><strong>Turun Kirjasto<\/strong> <strong>(NCC)<\/strong> \u2013 erikoiskeitti\u00f6t ja -kaapit, Turku<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-98420\" class=\"elementor-tab-title\" data-tab=\"20\" role=\"button\" aria-controls=\"elementor-tab-content-98420\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2006<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-98420\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"20\" role=\"region\" aria-labelledby=\"elementor-tab-title-98420\"><p><strong>Risteilyalus Royal Cruises<\/strong>\u2013 kasino tiskit, Art Gallery kalusteet, Turku<\/p><p><strong>Helsingin Yliopisto<\/strong>\u2013 hyllyst\u00f6t, Helsinki<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Referenssit Merianto on jo yli 20 vuotta suunnittelut sairaaloiden, terveyskeskusten, apteekkien, hotellien, museoiden, l\u00e4hetyst\u00f6jen, koulujen, p\u00e4iv\u00e4kotien, toimistorakennusten sek\u00e4 kotien kalustusta niin Virossa, Suomessa kuin muuallakin. T\u00e4rkeimpi\u00e4 asiakkaitamme ovat johtavat rakennusliikkeet, jotka ovat uskoneet suunnittelijoiden ja arkkitehtien loisteliaiden k\u00e4yt\u00e4nn\u00f6n toteutuksen meid\u00e4n teht\u00e4v\u00e4ksemme. Tavanomaisten kohteiden lis\u00e4ksi Merianto on toteuttanut sisustusprojekteja eritt\u00e4in vaativissa kohteissa. Esimerkkej\u00e4 kohteista: Finlandia-talo, Suomen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4574","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tehty ty\u00f6 - Merianto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.merianto.com\/fi\/tehty-tyo\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tehty ty\u00f6 - Merianto\" \/>\n<meta property=\"og:description\" content=\"Referenssit Merianto on jo yli 20 vuotta suunnittelut sairaaloiden, terveyskeskusten, apteekkien, hotellien, museoiden, l\u00e4hetyst\u00f6jen, koulujen, p\u00e4iv\u00e4kotien, toimistorakennusten sek\u00e4 kotien kalustusta niin Virossa, Suomessa kuin muuallakin. T\u00e4rkeimpi\u00e4 asiakkaitamme ovat johtavat rakennusliikkeet, jotka ovat uskoneet suunnittelijoiden ja arkkitehtien loisteliaiden k\u00e4yt\u00e4nn\u00f6n toteutuksen meid\u00e4n teht\u00e4v\u00e4ksemme. Tavanomaisten kohteiden lis\u00e4ksi Merianto on toteuttanut sisustusprojekteja eritt\u00e4in vaativissa kohteissa. Esimerkkej\u00e4 kohteista: Finlandia-talo, Suomen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.merianto.com\/fi\/tehty-tyo\/\" \/>\n<meta property=\"og:site_name\" content=\"Merianto\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-16T10:42:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Arvioitu lukuaika\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuuttia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.merianto.com\\\/fi\\\/tehty-tyo\\\/\",\"url\":\"https:\\\/\\\/www.merianto.com\\\/fi\\\/tehty-tyo\\\/\",\"name\":\"Tehty ty\u00f6 - Merianto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/merianto.com\\\/#website\"},\"datePublished\":\"2023-01-20T12:56:42+00:00\",\"dateModified\":\"2025-11-16T10:42:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.merianto.com\\\/fi\\\/tehty-tyo\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.merianto.com\\\/fi\\\/tehty-tyo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.merianto.com\\\/fi\\\/tehty-tyo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/merianto.com\\\/fi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tehty ty\u00f6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/merianto.com\\\/#website\",\"url\":\"https:\\\/\\\/merianto.com\\\/\",\"name\":\"Merianto\",\"description\":\"M\u00f6\u00f6bli ja sisustuse terviklahenduste juhtimine ja elluviimine\",\"publisher\":{\"@id\":\"https:\\\/\\\/merianto.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/merianto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/merianto.com\\\/#organization\",\"name\":\"Merianto O\u00dc\",\"url\":\"https:\\\/\\\/merianto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/merianto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/merianto.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Merianto_logo_rohvalge.svg\",\"contentUrl\":\"https:\\\/\\\/merianto.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Merianto_logo_rohvalge.svg\",\"width\":1042,\"height\":284,\"caption\":\"Merianto O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/merianto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tehty ty\u00f6 - Merianto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.merianto.com\/fi\/tehty-tyo\/","og_locale":"fi_FI","og_type":"article","og_title":"Tehty ty\u00f6 - Merianto","og_description":"Referenssit Merianto on jo yli 20 vuotta suunnittelut sairaaloiden, terveyskeskusten, apteekkien, hotellien, museoiden, l\u00e4hetyst\u00f6jen, koulujen, p\u00e4iv\u00e4kotien, toimistorakennusten sek\u00e4 kotien kalustusta niin Virossa, Suomessa kuin muuallakin. T\u00e4rkeimpi\u00e4 asiakkaitamme ovat johtavat rakennusliikkeet, jotka ovat uskoneet suunnittelijoiden ja arkkitehtien loisteliaiden k\u00e4yt\u00e4nn\u00f6n toteutuksen meid\u00e4n teht\u00e4v\u00e4ksemme. Tavanomaisten kohteiden lis\u00e4ksi Merianto on toteuttanut sisustusprojekteja eritt\u00e4in vaativissa kohteissa. Esimerkkej\u00e4 kohteista: Finlandia-talo, Suomen [&hellip;]","og_url":"https:\/\/www.merianto.com\/fi\/tehty-tyo\/","og_site_name":"Merianto","article_modified_time":"2025-11-16T10:42:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Arvioitu lukuaika":"10 minuuttia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.merianto.com\/fi\/tehty-tyo\/","url":"https:\/\/www.merianto.com\/fi\/tehty-tyo\/","name":"Tehty ty\u00f6 - Merianto","isPartOf":{"@id":"https:\/\/merianto.com\/#website"},"datePublished":"2023-01-20T12:56:42+00:00","dateModified":"2025-11-16T10:42:25+00:00","breadcrumb":{"@id":"https:\/\/www.merianto.com\/fi\/tehty-tyo\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.merianto.com\/fi\/tehty-tyo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.merianto.com\/fi\/tehty-tyo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/merianto.com\/fi\/"},{"@type":"ListItem","position":2,"name":"Tehty ty\u00f6"}]},{"@type":"WebSite","@id":"https:\/\/merianto.com\/#website","url":"https:\/\/merianto.com\/","name":"Merianto","description":"M\u00f6\u00f6bli ja sisustuse terviklahenduste juhtimine ja elluviimine","publisher":{"@id":"https:\/\/merianto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/merianto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/merianto.com\/#organization","name":"Merianto O\u00dc","url":"https:\/\/merianto.com\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/merianto.com\/#\/schema\/logo\/image\/","url":"https:\/\/merianto.com\/wp-content\/uploads\/2022\/09\/Merianto_logo_rohvalge.svg","contentUrl":"https:\/\/merianto.com\/wp-content\/uploads\/2022\/09\/Merianto_logo_rohvalge.svg","width":1042,"height":284,"caption":"Merianto O\u00dc"},"image":{"@id":"https:\/\/merianto.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/pages\/4574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/comments?post=4574"}],"version-history":[{"count":5,"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/pages\/4574\/revisions"}],"predecessor-version":[{"id":11102,"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/pages\/4574\/revisions\/11102"}],"wp:attachment":[{"href":"https:\/\/merianto.com\/fi\/wp-json\/wp\/v2\/media?parent=4574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}